{"id":593,"date":"2026-07-06T04:09:01","date_gmt":"2026-07-06T04:09:01","guid":{"rendered":"http:\/\/192.168.70.14\/wordpress\/?page_id=593"},"modified":"2026-07-14T08:36:43","modified_gmt":"2026-07-14T08:36:43","slug":"fuel-industry-supply","status":"publish","type":"page","link":"https:\/\/mywww.semicon.co.id\/index.php\/fuel-industry-supply\/","title":{"rendered":"Fuel Industry Supply"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"593\" class=\"elementor elementor-593\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abdfd9d e-con-full e-flex elementor-invisible e-con e-parent\" data-id=\"abdfd9d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c664530 e-con-full e-flex elementor-invisible e-con e-parent\" data-id=\"c664530\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-16dc615 e-con-full e-flex e-con e-child\" data-id=\"16dc615\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-cca8568 e-con-full e-flex e-con e-child\" data-id=\"cca8568\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cea45d8 elementor-widget elementor-widget-image\" data-id=\"cea45d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1920\" src=\"https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/06\/logo-semicon-01-scaled.webp\" class=\"attachment-full size-full wp-image-21\" alt=\"\" srcset=\"https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/06\/logo-semicon-01-scaled.webp 1920w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/06\/logo-semicon-01-300x300.webp 300w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/06\/logo-semicon-01-1024x1024.webp 1024w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/06\/logo-semicon-01-150x150.png 150w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/06\/logo-semicon-01-768x768.png 768w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/06\/logo-semicon-01-1536x1536.png 1536w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/06\/logo-semicon-01-2048x2048.png 2048w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/06\/elementor\/thumbs\/logo-semicon-01-scaled-rprbmh8zdu2lxfp5hbblptkqwlpoxvh3fh97dpcic0.webp 72w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b854f09 e-con-full e-flex e-con e-child\" data-id=\"b854f09\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7cd788 elementor-hidden-mobile elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"a7cd788\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_mobile\"\n\t\t\tdata-hamburger-icon=\"icon icon-menu1\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"767\"\n\t\t\tdata-close-on-anchor=\"\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                <svg class=\"ekit-menu-icon ekit-svg-icon icon-menu1\" viewBox=\"0 0 32 32\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M28 9.6h-24c-0.442 0-0.8-0.358-0.8-0.8s0.358-0.8 0.8-0.8h24c0.442 0 0.8 0.358 0.8 0.8s-0.358 0.8-0.8 0.8zM28 17.6h-24c-0.442 0-0.8-0.358-0.8-0.8s0.358-0.8 0.8-0.8h24c0.442 0 0.8 0.358 0.8 0.8s-0.358 0.8-0.8 0.8zM28 25.6h-24c-0.442 0-0.8-0.358-0.8-0.8s0.358-0.8 0.8-0.8h24c0.442 0 0.8 0.358 0.8 0.8s-0.358 0.8-0.8 0.8z\"><\/path><\/svg>            <\/button>\n            <div id=\"ekit-megamenu-menu-utama\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-menu-utama\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-icon\"><li id=\"menu-item-583\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-583 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/mywww.semicon.co.id\/\" class=\"ekit-menu-nav-link\">Beranda<\/a><\/li>\n<li id=\"menu-item-587\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-587 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/mywww.semicon.co.id\/index.php\/tentang-kami\/\" class=\"ekit-menu-nav-link\">Tentang Kami<\/a><\/li>\n<li id=\"menu-item-585\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-585 nav-item elementskit-dropdown-has top_position elementskit-dropdown-menu-full_width elementskit-megamenu-has elementskit-mobile-builder-content\" data-vertical-menu=\"\"><a href=\"https:\/\/mywww.semicon.co.id\/index.php\/layanan\/\" class=\"ekit-menu-nav-link\">Layanan<svg class=\"elementskit-submenu-indicator ekit-svg-icon icon-down-arrow1\" viewBox=\"0 0 32 32\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.582 8.495c-0.578-0.613-1.544-0.635-2.153-0.059l-13.43 12.723-13.428-12.723c-0.61-0.578-1.574-0.553-2.153 0.059-0.579 0.611-0.553 1.576 0.058 2.155l14.477 13.715c0.293 0.277 0.67 0.418 1.047 0.418s0.756-0.14 1.048-0.418l14.477-13.715c0.611-0.579 0.637-1.544 0.058-2.155z\"><\/path><\/svg><\/a><div class=\"elementskit-megamenu-panel\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1668\" class=\"elementor elementor-1668\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b903939 e-con-full e-flex e-con e-parent\" data-id=\"6b903939\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-277e8086 e-con-full e-flex e-con e-child\" data-id=\"277e8086\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-119da4a8 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"119da4a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5e93d30b e-con-full e-flex e-con e-child\" data-id=\"5e93d30b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_transition_duration&quot;:1000,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f6186ef e-con-full e-flex e-con e-child\" data-id=\"5f6186ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37114c53 elementor-hidden-mobile elementor-widget elementor-widget-elementskit-heading\" data-id=\"37114c53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">LAYANAN <span>KAMI<\/span><\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ed36e30 e-con-full e-flex e-con e-child\" data-id=\"6ed36e30\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-712e9f5f elementor-align-left elementor-widget elementor-widget-elementskit-page-list\" data-id=\"712e9f5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-page-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"elementor-icon-list-itemsfg \">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-18cb473 ekit_badge_left\" href=\"http:\/\/192.168.70.14\/wordpress\/index.php\/electrical-infrastructure-services\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t<svg class=\"ekit-svg-icon icon-right-arrow1\" viewBox=\"0 0 32 32\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20.757 16.4L8.036 2.971c-0.579-0.61-0.553-1.574 0.058-2.153 0.611-0.578 1.576-0.555 2.155 0.058l13.714 14.477c0.558 0.587 0.558 1.507 0 2.094L10.249 32.925c-0.3 0.317-0.703 0.475-1.106 0.475-0.376 0-0.753-0.139-1.048-0.418-0.611-0.579-0.637-1.544-0.058-2.153L20.757 16.4z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Catalyctic Converter Supply<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-fe5ff5e ekit_badge_left\" href=\"http:\/\/192.168.70.14\/wordpress\/index.php\/fuel-industry-supply\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t<svg class=\"ekit-svg-icon icon-right-arrow1\" viewBox=\"0 0 32 32\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20.757 16.4L8.036 2.971c-0.579-0.61-0.553-1.574 0.058-2.153 0.611-0.578 1.576-0.555 2.155 0.058l13.714 14.477c0.558 0.587 0.558 1.507 0 2.094L10.249 32.925c-0.3 0.317-0.703 0.475-1.106 0.475-0.376 0-0.753-0.139-1.048-0.418-0.611-0.579-0.637-1.544-0.058-2.153L20.757 16.4z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Fuel Industry Supply<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-03ca71e ekit_badge_left\" href=\"http:\/\/192.168.70.14\/wordpress\/index.php\/gas-engine-supply-installation\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t<svg class=\"ekit-svg-icon icon-right-arrow1\" viewBox=\"0 0 32 32\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20.757 16.4L8.036 2.971c-0.579-0.61-0.553-1.574 0.058-2.153 0.611-0.578 1.576-0.555 2.155 0.058l13.714 14.477c0.558 0.587 0.558 1.507 0 2.094L10.249 32.925c-0.3 0.317-0.703 0.475-1.106 0.475-0.376 0-0.753-0.139-1.048-0.418-0.611-0.579-0.637-1.544-0.058-2.153L20.757 16.4z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Gas Engine Supply &amp; Installation<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-368e22d0 elementor-align-left elementor-widget elementor-widget-elementskit-page-list\" data-id=\"368e22d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-page-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"elementor-icon-list-itemsfg \">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-0d779be ekit_badge_left\" href=\"http:\/\/192.168.70.14\/wordpress\/index.php\/layanan\/electrical-infrastructure-services\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t<svg class=\"ekit-svg-icon icon-right-arrow1\" viewBox=\"0 0 32 32\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20.757 16.4L8.036 2.971c-0.579-0.61-0.553-1.574 0.058-2.153 0.611-0.578 1.576-0.555 2.155 0.058l13.714 14.477c0.558 0.587 0.558 1.507 0 2.094L10.249 32.925c-0.3 0.317-0.703 0.475-1.106 0.475-0.376 0-0.753-0.139-1.048-0.418-0.611-0.579-0.637-1.544-0.058-2.153L20.757 16.4z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">Electrical Infrastructure Services<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon-list-item   \">\n\t\t\t\t\t\t<a class=\"elementor-repeater-item-fa41180 ekit_badge_left\" href=\"http:\/\/192.168.70.14\/wordpress\/index.php\/ups\/\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<div class=\"ekit_page_list_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t<svg class=\"ekit-svg-icon icon-right-arrow1\" viewBox=\"0 0 32 32\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20.757 16.4L8.036 2.971c-0.579-0.61-0.553-1.574 0.058-2.153 0.611-0.578 1.576-0.555 2.155 0.058l13.714 14.477c0.558 0.587 0.558 1.507 0 2.094L10.249 32.925c-0.3 0.317-0.703 0.475-1.106 0.475-0.376 0-0.753-0.139-1.048-0.418-0.611-0.579-0.637-1.544-0.058-2.153L20.757 16.4z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ekit_page_list_title_title\">UPS Flywheel Supply &amp; Installation<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/li>\n<li id=\"menu-item-586\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-586 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/mywww.semicon.co.id\/index.php\/portofolio\/\" class=\"ekit-menu-nav-link\">Portofolio<\/a><\/li>\n<li id=\"menu-item-584\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-584 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/mywww.semicon.co.id\/index.php\/kontak\/\" class=\"ekit-menu-nav-link\">Kontak<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><a class=\"elementskit-nav-logo\" href=\"https:\/\/mywww.semicon.co.id\" target=\"\" rel=\"\"><img src=\"http:\/\/192.168.70.14\/wordpress\/wp-content\/uploads\/2026\/07\/semicon-logo2-1.jpg\" title=\"\" alt=\"\" decoding=\"async\" \/><\/a><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4052f17 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"4052f17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\"\n\t\t\tdata-hamburger-icon=\"icon icon-menu-button-of-three-horizontal-lines\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"1024\"\n\t\t\tdata-close-on-anchor=\"no\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                <svg class=\"ekit-menu-icon ekit-svg-icon icon-menu-button-of-three-horizontal-lines\" viewBox=\"0 0 32 32\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M28.903 1.548h-25.806c-1.703 0-3.097 1.394-3.097 3.097s1.394 3.097 3.097 3.097h25.806c1.703 0 3.097-1.394 3.097-3.097s-1.394-3.097-3.097-3.097z\"><\/path><path d=\"M28.903 12.903h-25.806c-1.703 0-3.097 1.394-3.097 3.097s1.394 3.097 3.097 3.097h25.806c1.703 0 3.097-1.394 3.097-3.097s-1.394-3.097-3.097-3.097z\"><\/path><path d=\"M28.903 24.258h-25.806c-1.703 0-3.097 1.394-3.097 3.097s1.394 3.097 3.097 3.097h25.806c1.703 0 3.097-1.394 3.097-3.097s-1.394-3.097-3.097-3.097z\"><\/path><\/svg>            <\/button>\n            <div id=\"ekit-megamenu-menu-mobile\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-menu-mobile\" class=\"elementskit-navbar-nav elementskit-menu-po-left submenu-click-on-icon\"><li id=\"menu-item-2206\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2206 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\"><\/a><\/li>\n<li id=\"menu-item-2204\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2204 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\"><\/a><\/li>\n<li id=\"menu-item-2197\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2197 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\"><\/a><\/li>\n<li id=\"menu-item-2198\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2198 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\"><\/a><\/li>\n<li id=\"menu-item-2199\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2199 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\">Gas Engine Supply &#038; Installation<\/a><\/li>\n<li id=\"menu-item-2200\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2200 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\"><\/a><\/li>\n<li id=\"menu-item-2201\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2201 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\"><\/a><\/li>\n<li id=\"menu-item-2202\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2202 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\"><\/a><\/li>\n<li id=\"menu-item-2203\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2203 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\"><\/a><\/li>\n<li id=\"menu-item-2205\" class=\"menu-item menu-item-type- menu-item-object- menu-item-2205 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a class=\"ekit-menu-nav-link\">UPS Flywheel Supply &#038; Installation<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><a class=\"elementskit-nav-logo\" href=\"https:\/\/mywww.semicon.co.id\" target=\"\" rel=\"\"><img src=\"http:\/\/192.168.70.14\/wordpress\/wp-content\/uploads\/2026\/07\/cropped-semicon-logo2-1.jpg\" title=\"\" alt=\"\" decoding=\"async\" \/><\/a><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fd97b3c e-con-full e-flex e-con e-parent\" data-id=\"4fd97b3c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:969,&quot;url&quot;:&quot;http:\\\/\\\/192.168.70.14\\\/wordpress\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Gas.webp&quot;},{&quot;id&quot;:972,&quot;url&quot;:&quot;http:\\\/\\\/192.168.70.14\\\/wordpress\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Main-2.webp&quot;}],&quot;background_slideshow_transition_duration&quot;:2500,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-71705bb3 e-con-full e-flex e-con e-child\" data-id=\"71705bb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4c5b4e5 e-con-full eael_liquid_glass-effect2 e-flex eael_liquid_glass_shadow-effect1 elementor-invisible e-con e-child\" data-id=\"4c5b4e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2e4c72 elementor-hidden-mobile elementor-widget elementor-widget-eael-breadcrumbs\" data-id=\"e2e4c72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-breadcrumbs\">\n\t\t\t<div class=\"eael-breadcrumbs__content\"><a href=\"https:\/\/mywww.semicon.co.id\">Home<\/a> <span class=\"eael-breadcrumb-separator\">&gt;<\/span> <span class = \"eael-current\">Page<\/span><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d23628e elementor-widget elementor-widget-heading\" data-id=\"d23628e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fuel Industry Supply<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<p class=\"e-b78bb16-1651750 e-paragraph-base\" data-interaction-id=\"b78bb16\">Waktu henti itu mahal biayanya. Kami merancang dan memelihara infrastruktur tegangan tinggi yang benar-benar handal dan minim mengalami kegagalan.<\/p>\n\t\t\t\t<div class=\"elementor-element elementor-element-0137a72 elementor-widget elementor-widget-button\" data-id=\"0137a72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pesan Sekarang <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ef56db3 e-con-full e-flex e-con e-parent\" data-id=\"6ef56db3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9012d39 e-grid e-con-full elementor-invisible e-con e-child\" data-id=\"9012d39\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6e8882aa e-con-full kotak-visi-misi e-flex e-con e-child\" data-id=\"6e8882aa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5fc5ff47 e-con-full e-flex e-con e-child\" data-id=\"5fc5ff47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fc9a59b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5fc9a59b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bolt\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 160H180.6l42.6-129.8C227.2 15 215.7 0 200 0H56C44 0 33.8 8.9 32.2 20.8l-32 240C-1.7 275.2 9.5 288 24 288h118.7L96.6 482.5c-3.6 15.2 8 29.5 23.3 29.5 8.4 0 16.4-4.4 20.8-12l176-304c9.3-15.9-2.2-36-20.7-36z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ccfa291 e-con-full e-flex e-con e-child\" data-id=\"4ccfa291\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-27ae85b7 e-con-full e-flex e-con e-child\" data-id=\"27ae85b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33ee0702 e-transform elementor-widget elementor-widget-elementskit-heading\" data-id=\"33ee0702\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title  ekit-heading__title-has-border start\">Tingkatkan Efisiensi Operasional\u200b<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5519ba9 e-con-full e-flex e-con e-child\" data-id=\"5519ba9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<p class=\"e-3fe6fb78-a15d4ab e-paragraph-base\" data-interaction-id=\"3fe6fb78\">Cegah pemborosan anggaran. Kami mengoptimalkan arsitektur kelistrikan Anda untuk distribusi presisi, tegangan stabil, dan efisiensi operasional maksimum.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f843853 e-con-full kotak-visi-misi e-flex e-con e-child\" data-id=\"4f843853\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-15f6f2c0 e-con-full e-flex e-con e-child\" data-id=\"15f6f2c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-191c0c84 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"191c0c84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-shield-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M466.5 83.7l-192-80a48.15 48.15 0 0 0-36.9 0l-192 80C27.7 91.1 16 108.6 16 128c0 198.5 114.5 335.7 221.5 380.3 11.8 4.9 25.1 4.9 36.9 0C360.1 472.6 496 349.3 496 128c0-19.4-11.7-36.9-29.5-44.3zM256.1 446.3l-.1-381 175.9 73.3c-3.3 151.4-82.1 261.1-175.8 307.7z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73671197 e-con-full e-flex e-con e-child\" data-id=\"73671197\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-585356fe e-con-full e-flex e-con e-child\" data-id=\"585356fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d933ca3 e-transform elementor-widget elementor-widget-elementskit-heading\" data-id=\"1d933ca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title  ekit-heading__title-has-border start\">Keamanan Sistem Tanpa Kompromi<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65b02be4 e-con-full e-flex e-con e-child\" data-id=\"65b02be4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<p class=\"e-1cdfc4f5-23b385f e-paragraph-base\" data-interaction-id=\"1cdfc4f5\">Jangan tunggu bencana terjadi. Kami menerapkan standar proteksi tingkat tinggi untuk mencegah korsleting dan lonjakan arus fatal sebelum melumpuhkan aset Anda.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-598ae2aa e-con-full kotak-visi-misi e-flex e-con e-child\" data-id=\"598ae2aa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-16d3c255 e-con-full e-flex e-con e-child\" data-id=\"16d3c255\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-416e0b6f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"416e0b6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-expand-arrows-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 344v112a23.94 23.94 0 0 1-24 24H312c-21.39 0-32.09-25.9-17-41l36.2-36.2L224 295.6 116.77 402.9 153 439c15.09 15.1 4.39 41-17 41H24a23.94 23.94 0 0 1-24-24V344c0-21.4 25.89-32.1 41-17l36.19 36.2L184.46 256 77.18 148.7 41 185c-15.1 15.1-41 4.4-41-17V56a23.94 23.94 0 0 1 24-24h112c21.39 0 32.09 25.9 17 41l-36.2 36.2L224 216.4l107.23-107.3L295 73c-15.09-15.1-4.39-41 17-41h112a23.94 23.94 0 0 1 24 24v112c0 21.4-25.89 32.1-41 17l-36.19-36.2L263.54 256l107.28 107.3L407 327.1c15.1-15.2 41-4.5 41 16.9z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70d96281 e-con-full e-flex e-con e-child\" data-id=\"70d96281\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7a3ac3c6 e-con-full e-flex e-con e-child\" data-id=\"7a3ac3c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b03b47e e-transform elementor-widget elementor-widget-elementskit-heading\" data-id=\"2b03b47e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title  ekit-heading__title-has-border start\">Skalabilitas Kuat, Pangkas Biaya<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75eb02a2 e-con-full e-flex e-con e-child\" data-id=\"75eb02a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<p class=\"e-38113b71-5d38374 e-paragraph-base\" data-interaction-id=\"38113b71\">Ekspansi kapasitas tanpa membongkar infrastruktur dasar. Kami merancang panel distribusi untuk menangani beban tinggi dan menekan kerugian akibat downtime hingga nol.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c8ac1fb e-con-full e-flex e-con e-parent\" data-id=\"2c8ac1fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1180d49c e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1180d49c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-517fd89f elementor-widget elementor-widget-elementskit-heading\" data-id=\"517fd89f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<span class='ekit-heading__shadow-text'>\n\t\t\t\t\tLayanan\t\t\t\t<\/span>\n\t\t\t<h2 class=\"ekit-heading--title elementskit-section-title \">Layanan<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-151d3978 e-transform elementor-widget elementor-widget-elementskit-heading\" data-id=\"151d3978\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Layanan <span>Layanan Infrastruktur Kelistrikan<\/span> Di Semicon<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18ab05c1 e-con-full e-flex e-con e-child\" data-id=\"18ab05c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3d5f72b5 e-grid e-con-full elementor-invisible e-con e-child\" data-id=\"3d5f72b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1016e00d ekit-equal-height-enable e-transform elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"1016e00d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text-left icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg aria-hidden=\"true\" class=\"elementkit-infobox-icon e-font-icon-svg e-fas-screwdriver\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 0L320 96v62.06l-83.03 83.03c6.79 4.25 13.27 9.06 19.07 14.87 5.8 5.8 10.62 12.28 14.87 19.07L353.94 192H416l96-128-64-64zM128 278.59L10.92 395.67c-14.55 14.55-14.55 38.15 0 52.71l52.7 52.7c14.56 14.56 38.15 14.56 52.71 0L233.41 384c29.11-29.11 29.11-76.3 0-105.41s-76.3-29.11-105.41 0z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Layanan generator                <\/h3>\n                        \t\t  \t<p>Pastikan operasional Anda tetap berjalan lancar saat jaringan listrik padam dengan solusi generator menyeluruh kami.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fae41ac ekit-equal-height-enable e-transform elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"6fae41ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text-left icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg aria-hidden=\"true\" class=\"elementkit-infobox-icon e-font-icon-svg e-fas-bolt\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 160H180.6l42.6-129.8C227.2 15 215.7 0 200 0H56C44 0 33.8 8.9 32.2 20.8l-32 240C-1.7 275.2 9.5 288 24 288h118.7L96.6 482.5c-3.6 15.2 8 29.5 23.3 29.5 8.4 0 16.4-4.4 20.8-12l176-304c9.3-15.9-2.2-36-20.7-36z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Distribusi Daya                <\/h3>\n                        \t\t  \t<p>Pastikan operasional Anda tetap berjalan lancar saat jaringan listrik padam dengan solusi generator menyeluruh kami.\n\n<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19570304 ekit-equal-height-enable e-transform elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"19570304\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text-left icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg aria-hidden=\"true\" class=\"elementkit-infobox-icon e-font-icon-svg e-fas-bolt\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 160H180.6l42.6-129.8C227.2 15 215.7 0 200 0H56C44 0 33.8 8.9 32.2 20.8l-32 240C-1.7 275.2 9.5 288 24 288h118.7L96.6 482.5c-3.6 15.2 8 29.5 23.3 29.5 8.4 0 16.4-4.4 20.8-12l176-304c9.3-15.9-2.2-36-20.7-36z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Instalasi kabel listrik                <\/h3>\n                        \t\t  \t<p>Eksekusi sempurna dari tahap awal hingga akhir. Kami menyediakan instalasi tegangan menengah dan rendah yang aman serta memenuhi standar regulasi, guna memastikan pasokan daya yang andal bagi bisnis Anda setiap harinya.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fd6a4d0 ekit-equal-height-enable e-transform elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"1fd6a4d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text-left icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg aria-hidden=\"true\" class=\"elementkit-infobox-icon e-font-icon-svg e-fas-bolt\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 160H180.6l42.6-129.8C227.2 15 215.7 0 200 0H56C44 0 33.8 8.9 32.2 20.8l-32 240C-1.7 275.2 9.5 288 24 288h118.7L96.6 482.5c-3.6 15.2 8 29.5 23.3 29.5 8.4 0 16.4-4.4 20.8-12l176-304c9.3-15.9-2.2-36-20.7-36z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    kendali &amp; cadangan                <\/h3>\n                        \t\t  \t<p>Instalasi listrik yang aman dan memenuhi standar teknis, dirancang untuk menyuplai daya bagi fasilitas Anda secara optimal sejak tahap awal pembangunan.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48180c8b e-con-full e-flex e-con e-parent\" data-id=\"48180c8b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5ea0de9a e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"5ea0de9a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-141375f4 elementor-widget elementor-widget-elementskit-heading\" data-id=\"141375f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<span class='ekit-heading__shadow-text'>\n\t\t\t\t\tPORTOFOLIO\t\t\t\t<\/span>\n\t\t\t<h2 class=\"ekit-heading--title elementskit-section-title  ekit-heading__title-has-border start\">KARYA KAMI<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ebb3b9d elementor-widget elementor-widget-elementskit-heading\" data-id=\"3ebb3b9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">PENGALAMAN  <span>PROJECT<\/span><\/h1><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-622b8a21 e-transform elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"622b8a21\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tLihat Detail Porto<svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-326c5a0c e-con-full e-flex e-con e-child\" data-id=\"326c5a0c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2ecb4959 e-grid e-con-full animated-slow elementor-invisible e-con e-child\" data-id=\"2ecb4959\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63d81b12 e-transform ekit-equal-height-disable elementor-widget elementor-widget-elementskit-image-box\" data-id=\"63d81b12\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-left simple-card\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-left\">\n\n                    <img decoding=\"async\" width=\"1062\" height=\"809\" src=\"https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2.avif\" class=\"attachment-full size-full wp-image-74\" alt=\"\" srcset=\"https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2.avif 1062w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2-300x229.avif 300w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2-1024x780.avif 1024w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2-768x585.avif 768w\" sizes=\"(max-width: 1062px) 100vw, 1062px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        Pasokan Bahan Bakar ke STT IRIS Tahap 3 untuk Genset 2x200 kVA\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Instalasi sistem HVAC dan kelistrikan redundansi tinggi untuk fasilitas penyimpanan data skala besar                    <\/div>\n                                    <\/div>\n\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd704d6 e-transform ekit-equal-height-disable elementor-widget elementor-widget-elementskit-image-box\" data-id=\"dd704d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-left simple-card\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-left\">\n\n                    <img decoding=\"async\" width=\"1062\" height=\"809\" src=\"https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2.avif\" class=\"attachment-full size-full wp-image-74\" alt=\"\" srcset=\"https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2.avif 1062w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2-300x229.avif 300w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2-1024x780.avif 1024w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2-768x585.avif 768w\" sizes=\"(max-width: 1062px) 100vw, 1062px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        Pasokan Bahan Bakar ke STT IRIS Tahap 3 untuk Genset 2x200 kVA\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Instalasi sistem HVAC dan kelistrikan redundansi tinggi untuk fasilitas penyimpanan data skala besar                    <\/div>\n                                    <\/div>\n\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a923959 e-transform ekit-equal-height-disable elementor-widget elementor-widget-elementskit-image-box\" data-id=\"2a923959\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-left simple-card\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-left\">\n\n                    <img decoding=\"async\" width=\"1062\" height=\"809\" src=\"https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2.avif\" class=\"attachment-full size-full wp-image-74\" alt=\"\" srcset=\"https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2.avif 1062w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2-300x229.avif 300w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2-1024x780.avif 1024w, https:\/\/mywww.semicon.co.id\/wp-content\/uploads\/2026\/07\/2-768x585.avif 768w\" sizes=\"(max-width: 1062px) 100vw, 1062px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        Pasokan Bahan Bakar ke STT IRIS Tahap 3 untuk Genset 2x200 kVA\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Instalasi sistem HVAC dan kelistrikan redundansi tinggi untuk fasilitas penyimpanan data skala besar                    <\/div>\n                                    <\/div>\n\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7445ac8e e-con-full e-flex e-con e-parent\" data-id=\"7445ac8e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-32616c9d e-con-full e-flex e-con e-child\" data-id=\"32616c9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4d198b69 e-con-full e-flex e-con e-child\" data-id=\"4d198b69\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7cdeb3b7 elementor-widget elementor-widget-heading\" data-id=\"7cdeb3b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Semicon Internusa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35f2c583 elementor-widget elementor-widget-heading\" data-id=\"35f2c583\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00a9 2026 Semicon Internusa. All Rights Reserved.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c80eb3d e-con-full e-flex e-con e-child\" data-id=\"6c80eb3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-934851d e-con-full e-flex e-con e-child\" data-id=\"934851d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bed322f elementor-widget elementor-widget-heading\" data-id=\"1bed322f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kebijakan Privasi<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34d1e96a e-con-full e-flex e-con e-child\" data-id=\"34d1e96a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-706b3a49 elementor-widget elementor-widget-heading\" data-id=\"706b3a49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12f57e27 elementor-widget elementor-widget-heading\" data-id=\"12f57e27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d6359f0 elementor-widget elementor-widget-heading\" data-id=\"1d6359f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aecef49 elementor-widget elementor-widget-heading\" data-id=\"7aecef49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46a77e98 elementor-widget elementor-widget-heading\" data-id=\"46a77e98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6fb33fbf e-con-full e-flex e-con e-child\" data-id=\"6fb33fbf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4460b2f3 elementor-widget elementor-widget-heading\" data-id=\"4460b2f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kebijakan Privasi<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc4eaaf e-con-full e-flex e-con e-child\" data-id=\"dc4eaaf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6018fcd6 elementor-widget elementor-widget-heading\" data-id=\"6018fcd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67a40f00 elementor-widget elementor-widget-heading\" data-id=\"67a40f00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f317645 elementor-widget elementor-widget-heading\" data-id=\"1f317645\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-457b00c4 elementor-widget elementor-widget-heading\" data-id=\"457b00c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b050acc elementor-widget elementor-widget-heading\" data-id=\"2b050acc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorem Ipsum: Lorem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Beranda Tentang Kami Layanan LAYANAN KAMI Catalyctic Converter Supply Fuel Industry Supply Gas Engine Supply &amp; Installation Electrical Infrastructure Services UPS Flywheel Supply &amp; Installation Portofolio Kontak X Beranda Kontak Layanan Electrical Infrastructure Services Catalyctic Converter Supply Gas Engine Supply &#038; Installation UPS Flywheel Supply &#038; Installation Fuel Industry Supply Portofolio Tentang Kami X Home [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-593","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mywww.semicon.co.id\/index.php\/wp-json\/wp\/v2\/pages\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mywww.semicon.co.id\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mywww.semicon.co.id\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mywww.semicon.co.id\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mywww.semicon.co.id\/index.php\/wp-json\/wp\/v2\/comments?post=593"}],"version-history":[{"count":49,"href":"https:\/\/mywww.semicon.co.id\/index.php\/wp-json\/wp\/v2\/pages\/593\/revisions"}],"predecessor-version":[{"id":1934,"href":"https:\/\/mywww.semicon.co.id\/index.php\/wp-json\/wp\/v2\/pages\/593\/revisions\/1934"}],"wp:attachment":[{"href":"https:\/\/mywww.semicon.co.id\/index.php\/wp-json\/wp\/v2\/media?parent=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}